
{"id":18872,"date":"2024-04-15T09:06:00","date_gmt":"2024-04-15T08:06:00","guid":{"rendered":"https:\/\/www.rosello-mallol.com\/?p=18872"},"modified":"2024-04-13T07:33:28","modified_gmt":"2024-04-13T06:33:28","slug":"base-legitimadora","status":"publish","type":"post","link":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/","title":{"rendered":"La Base legitimadora para el Tratamiento de Datos Personales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el mundo de la protecci\u00f3n de datos, una de las cuestiones fundamentales es la base legitimadora sobre la cual se realiza el tratamiento de datos personales. En el marco del <strong>Reglamento General de Protecci\u00f3n de Datos<\/strong> (RGPD) de la Uni\u00f3n Europea , existen varias bases legitimadoras (art. 6 RGPD) que permiten a las organizaciones recopilar, utilizar y compartir datos personales de manera legal y \u00e9tica. En este post, exploraremos las diferentes bases legitimadoras y su importancia en el tratamiento de datos. Entenderlas y aplicarlas adecuadamente es b\u00e1sico para cumplir otras obligaciones b\u00e1sicas como el tiempo de retenci\u00f3n de los datos, redactar la pol\u00edtica de privacidad, elaborar el <a href=\"https:\/\/www.rosello-mallol.com\/es\/registro-actividad-del-tratamiento\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>registro de actividades<\/strong><\/a>, etc&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A continuaci\u00f3n exponemos las bases legitimadoras aplicables a las entidades privadas:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El Consentimiento del Titular de los Datos: la base legitimadora m\u00e1s habitual.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El consentimiento es una de las bases legitimadoras m\u00e1s conocidas y utilizadas para el tratamiento de datos personales, aunque <strong>no la \u00fanica<\/strong>. Seg\u00fan el RGPD, el consentimiento debe ser libre, espec\u00edfico, informado e inequ\u00edvoco, y los individuos tienen el derecho de retirar su consentimiento en cualquier momento. Es importante que las organizaciones obtengan un consentimiento <strong>claro y expl\u00edcito<\/strong>, nunca t\u00e1cito, antes de procesar los datos personales de los individuos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar que no es la \u00fanica base legitimadora, la falta de consentimiento para el tratamiento de datos suele ser uno de los grandes argumentos de la <strong>Agencia Espa\u00f1ola de Protecci\u00f3n de Datos<\/strong> para imponer sanciones. Una reciente, <a href=\"https:\/\/www.aepd.es\/documento\/ps-00307-2023.pdf\"><strong>est<\/strong><\/a><a href=\"https:\/\/www.aepd.es\/documento\/ps-00307-2023.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>a<\/strong><\/a> a Orange por facilitar a un tercero no autorizado, copia de una tarjeta SIM, sin consentimiento del titular.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La ejecuci\u00f3n de un contrato en el que interesado es parte<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Otra base legitimadora para el tratamiento de datos es la ejecuci\u00f3n de un contrato. Cuando el tratamiento de datos es necesario <strong>para cumplir con un contrato<\/strong> del cual el individuo forma parte, <strong>no se requiere consentimiento adicional<\/strong>. Sin embargo, el tratamiento debe ser necesario para el cumplimiento del contrato y estar relacionado con el mismo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cumplimiento de una Obligaci\u00f3n Legal<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El tratamiento de datos tambi\u00e9n puede ser necesario para el cumplimiento de una obligaci\u00f3n legal a la que est\u00e1 sujeta la organizaci\u00f3n, empresa o entidad. Esto incluye situaciones en las que el tratamiento es necesario para el cumplimiento de obligaciones legales o regulatorias, como por ejemplo, el cumplimiento de obligaciones laborales o fiscales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El inter\u00e9s leg\u00edtimo: la base legitimadora para el marketing a clientes vigentes.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El tratamiento de datos tambi\u00e9n puede basarse en los intereses leg\u00edtimos perseguidos por la organizaci\u00f3n . Sin embargo, es importante <strong>equilibrar estos intereses<\/strong> con los derechos y libertades fundamentales de los individuos. Las organizaciones deben llevar a cabo una evaluaci\u00f3n de impacto de protecci\u00f3n de datos (EIPD) para determinar si sus intereses leg\u00edtimos prevalecen sobre los derechos de privacidad de los individuos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los intereses leg\u00edtimos como base legitimadora se incluye el uso de los datos con fines de marketing, en relaci\u00f3n a clientes vigentes y para ofrecer productos o servicios similares y de la misma empresa con la que existe la relaci\u00f3n contractual.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Protecci\u00f3n de Intereses Vitales<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En situaciones donde el tratamiento de datos es necesario para proteger intereses vitales del individuo o de otra persona f\u00edsica, esta base legal puede ser aplicable. Por ejemplo, en casos de emergencia m\u00e9dica o situaciones de vida o muerte, las organizaciones pueden procesar datos personales sin consentimiento para proteger la salud y seguridad de los individuos involucrados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusi\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En resumen, entender la base legitimadora para el tratamiento de datos es fundamental para garantizar el cumplimiento de las regulaciones de protecci\u00f3n de datos y proteger los derechos de privacidad de los individuos. Al seleccionar la base legitimadora adecuada, las organizaciones pueden asegurar que su tratamiento de datos sea transparente, \u00e9tico y legalmente s\u00f3lido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si necesitas m\u00e1s informaci\u00f3n, \u00a1contacta con nosotros!:<\/p>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\"><p class=\"wpcf7-contact-form-not-found\"><strong>Error:<\/strong> Formulario de contacto no encontrado.<\/p><\/div>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><small><strong>Denominaci\u00f3n social<\/strong><\/small><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><small>LEGAL IT GLOBAL 2017, SLP<br><strong>Finalidad<br><\/strong>Prestar el servicio.<br>Env\u00edo del Bolet\u00edn informativo.<br><strong>Legitimizaci\u00f3n<br><\/strong>Cumplimiento de la prestaci\u00f3n del servicio.<br>Consentimiento.<br><strong>Destinatarios<\/strong><br>Tus datos no ser\u00e1n compartidos con ning\u00fan tercero, salvo a<\/small> <small>aquellos proveedores de servicios con los que disponemos de un contrato de servicios vigente.<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el mundo de la protecci\u00f3n de datos, una de las cuestiones fundamentales es la base legitimadora sobre la cual se realiza el tratamiento de datos personales. En el marco del Reglamento General de Protecci\u00f3n de Datos (RGPD) de la Uni\u00f3n Europea , existen varias bases legitimadoras (art. 6 RGPD) que permiten a las organizaciones [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":18873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_joinchat":[],"footnotes":""},"categories":[209],"tags":[241,1328,230,399,612,236],"class_list":["post-18872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-aepd-es","tag-base-legitimadora","tag-gdpr-es","tag-privacidad-2","tag-proteccion-datos-2","tag-rgpd-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La Base legitimadora para el Tratamiento de Datos Personales | Rosell\u00f3 Mallol<\/title>\n<meta name=\"description\" content=\"Entiende la base legitimadora del RGPD para el tratamiento de datos de car\u00e1cter personal y apl\u00edcala adecuadamente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Base legitimadora para el Tratamiento de Datos Personales\" \/>\n<meta property=\"og:description\" content=\"En el mundo de la protecci\u00f3n de datos, una de las cuestiones fundamentales es la base legitimadora sobre la cual se realiza el tratamiento de datos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/\" \/>\n<meta property=\"og:site_name\" content=\"Rosell\u00f3 Mallol\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-15T08:06:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/checklist-7658401_1280.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"915\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"DespatxRM\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vic_rosello\" \/>\n<meta name=\"twitter:site\" content=\"@vic_rosello\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"DespatxRM\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La Base legitimadora para el Tratamiento de Datos Personales | Rosell\u00f3 Mallol","description":"Entiende la base legitimadora del RGPD para el tratamiento de datos de car\u00e1cter personal y apl\u00edcala adecuadamente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/","og_locale":"es_ES","og_type":"article","og_title":"La Base legitimadora para el Tratamiento de Datos Personales","og_description":"En el mundo de la protecci\u00f3n de datos, una de las cuestiones fundamentales es la base legitimadora sobre la cual se realiza el tratamiento de datos","og_url":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/","og_site_name":"Rosell\u00f3 Mallol","article_published_time":"2024-04-15T08:06:00+00:00","og_image":[{"width":1280,"height":915,"url":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/checklist-7658401_1280.png","type":"image\/png"}],"author":"DespatxRM","twitter_card":"summary_large_image","twitter_creator":"@vic_rosello","twitter_site":"@vic_rosello","twitter_misc":{"Escrito por":"DespatxRM","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/#article","isPartOf":{"@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/"},"author":{"name":"DespatxRM","@id":"https:\/\/www.rosello-mallol.com\/es\/#\/schema\/person\/594f32415eefd4edf26d6f2f2ad25ad3"},"headline":"La Base legitimadora para el Tratamiento de Datos Personales","datePublished":"2024-04-15T08:06:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/"},"wordCount":733,"publisher":{"@id":"https:\/\/www.rosello-mallol.com\/es\/#organization"},"image":{"@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/checklist-7658401_1280.png","keywords":["aepd","base legitimadora","GDPR","privacidad","proteccion datos","RGPD"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/","url":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/","name":"La Base legitimadora para el Tratamiento de Datos Personales | Rosell\u00f3 Mallol","isPartOf":{"@id":"https:\/\/www.rosello-mallol.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/#primaryimage"},"image":{"@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/checklist-7658401_1280.png","datePublished":"2024-04-15T08:06:00+00:00","description":"Entiende la base legitimadora del RGPD para el tratamiento de datos de car\u00e1cter personal y apl\u00edcala adecuadamente.","breadcrumb":{"@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/#primaryimage","url":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/checklist-7658401_1280.png","contentUrl":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/checklist-7658401_1280.png","width":1280,"height":915,"caption":"Base legitimadora"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosello-mallol.com\/es\/base-legitimadora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rosello-mallol.com\/es\/"},{"@type":"ListItem","position":2,"name":"La Base legitimadora para el Tratamiento de Datos Personales"}]},{"@type":"WebSite","@id":"https:\/\/www.rosello-mallol.com\/es\/#website","url":"https:\/\/www.rosello-mallol.com\/es\/","name":"Rosell\u00f3 Mallol","description":"Despatx advocats experts en TIC i Protecci\u00f3 de dades","publisher":{"@id":"https:\/\/www.rosello-mallol.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosello-mallol.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rosello-mallol.com\/es\/#organization","name":"Rosell\u00f3 Mallol - Advocats especialistes en dret digital","url":"https:\/\/www.rosello-mallol.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rosello-mallol.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/logo-definitiu-web.png","contentUrl":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/logo-definitiu-web.png","width":4000,"height":736,"caption":"Rosell\u00f3 Mallol - Advocats especialistes en dret digital"},"image":{"@id":"https:\/\/www.rosello-mallol.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/vic_rosello","https:\/\/www.instagram.com\/rosellomallol\/","https:\/\/www.linkedin.com\/in\/victorrosello\/","https:\/\/www.youtube.com\/channel\/UCxcqAdksWzsEaZ5UYoFJd0Q\/featured"]},{"@type":"Person","@id":"https:\/\/www.rosello-mallol.com\/es\/#\/schema\/person\/594f32415eefd4edf26d6f2f2ad25ad3","name":"DespatxRM","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/514c88e026ea3d52a2f2e8160d0a6a33ddffa36275325c971e52c19709a18d74?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/514c88e026ea3d52a2f2e8160d0a6a33ddffa36275325c971e52c19709a18d74?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/514c88e026ea3d52a2f2e8160d0a6a33ddffa36275325c971e52c19709a18d74?s=96&d=mm&r=g","caption":"DespatxRM"},"url":"https:\/\/www.rosello-mallol.com\/es\/author\/despatxrm\/"}]}},"jetpack_featured_media_url":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/checklist-7658401_1280.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/posts\/18872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/comments?post=18872"}],"version-history":[{"count":0,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/posts\/18872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/media\/18873"}],"wp:attachment":[{"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/media?parent=18872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/categories?post=18872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/tags?post=18872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}