
{"id":18263,"date":"2023-02-16T10:30:48","date_gmt":"2023-02-16T09:30:48","guid":{"rendered":"https:\/\/www.rosello-mallol.com\/?p=18263"},"modified":"2023-02-16T10:30:51","modified_gmt":"2023-02-16T09:30:51","slug":"datos-anonimos","status":"publish","type":"post","link":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/","title":{"rendered":"Datos an\u00f3nimos: \u00bfQu\u00e9 son?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De acuerdo a lo establecido en el <strong><span style=\"text-decoration: underline;\">Considerando 26 del RGPD<\/span><\/strong>, la normativa de protecci\u00f3n de datos y el RGPD en particular <strong>no se aplica<\/strong> a los datos an\u00f3nimos o anonimizados. Pero, \u00bfqu\u00e9 son y cu\u00e1ndo puede entenderse que un conjunto de informaci\u00f3n tiene esta caracter\u00edstica? Trataremos de resolverlo en este post:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 son los datos an\u00f3nimos o anonimizados?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los datos o informaci\u00f3n an\u00f3nima o anonimizada es aquella que <span style=\"text-decoration: underline;\"><strong>hace imposible la identificaci\u00f3n de una persona<\/strong><\/span> f\u00edsica a trav\u00e9s de distintas t\u00e9cnicas que \u201cseparan\u201d la informaci\u00f3n que identifica a alguien de aquellos datos que impiden su identificaci\u00f3n. La UE analiz\u00f3 en su d\u00eda las distintas t\u00e9cnicas de anonimizaci\u00f3n en este formato:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Marta \/ Localidad \/ CP \/ Edad \/ Enfermedad: es informaci\u00f3n de una persona identificable.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Localidad \/ CP \/ Edad \/ Enfermedad: es informaci\u00f3n an\u00f3nima.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Esta imposibilidad de relacionar la informaci\u00f3n anonimizada con su propietario originario debe analizarse desde la perspectiva de que no exista una \u201cprobabilidad razonable\u201d a que esta identificaci\u00f3n se produzca.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello, deben valorarse criterios como: el tiempo que requerir\u00eda tal proceso de reidentificaci\u00f3n, los costes asociados al mismo o los medios tecnol\u00f3gicos que se requerir\u00edan para conseguir tal fin.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como decimos, <strong>el RGPD no es aplicable a la informaci\u00f3n an\u00f3nima<\/strong>, por lo que resulta esencial que, en el caso que queramos justificar la no necesidad de cumplir el RGPD bas\u00e1ndonos en que tratamos informaci\u00f3n an\u00f3nima, que podamos justificar que esta <strong>caracter\u00edstica efectivamente se cumple<\/strong>, resultando imposible identificar o reidentificar a la persona con la que originariamente estaba relacionada la informaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 diferencia hay entre los an\u00f3nimos y los seudonimizados?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La <strong>informaci\u00f3n seudonimizada no permite la identificaci\u00f3n de personas<\/strong>, salvo que se utilice informaci\u00f3n adicional, siempre que dicha informaci\u00f3n figure de manera separada o independiente.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, por ejemplo, disponer de informaci\u00f3n personal de alguien, asociada a un c\u00f3digo y luego y por separado, tener la informaci\u00f3n de a qui\u00e9n pertenece ese c\u00f3digo, no es informaci\u00f3n an\u00f3nima sino seudonimizada. La diferencia es esencial pues a <strong>los datos seudonimizados s\u00ed se les aplica el RGPD<\/strong>, por lo que deber\u00e1n tenerse en cuenta todos los requisitos que establece.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La AEPD concreta estas <strong><a href=\"https:\/\/www.aepd.es\/es\/prensa-y-comunicacion\/blog\/anonimizacion-y-seudonimizacion\" target=\"_blank\" rel=\"noreferrer noopener\">medidas<\/a><\/strong> en 4 puntos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Que el proceso impida la identificaci\u00f3n de la persona, sin disponer de la informaci\u00f3n adicional.<\/li>\n\n\n\n<li>La aplicaci\u00f3n de los principios b\u00e1sicos del RGPD: <strong>finalidad, periodo de conservaci\u00f3n y la comunicaci\u00f3n de datos seudonimizados<\/strong>.<\/li>\n\n\n\n<li>Aplicar medidas adecuadas en funci\u00f3n del riesgo que implique el tratamiento de estos datos.<\/li>\n\n\n\n<li>Aplicar medidas t\u00e9cnicas y organizativas para evitar brechas de seguridad, tanto de los datos seudonimizados como de la informaci\u00f3n adicional.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En definitiva, el tratamiento de datos correctamente anonimizados es una <strong>muy buena f\u00f3rmula para evitar el cumplimiento del RGPD<\/strong>, con las ventajas que esto supone.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicho esto, s\u00ed que deber\u00edas hacerte las siguientes preguntas para tu proyecto o empresa:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfEs posible conseguir la finalidad perseguida con la recogida de datos, anonimiz\u00e1ndolos? Si la respuesta es s\u00ed, <strong>no dudes en hacerlo<\/strong>. Un principio b\u00e1sico de la normativa es tratar cuantos menos datos mejor para conseguir un fin y si \u00e9stos pueden ser an\u00f3nimos sin identificar a nadie, mucho mejor.<\/li>\n\n\n\n<li>Si puedo tratar datos de manera an\u00f3nima, \u00bfpuedo asegurar que resulta imposible reidentificar a personas f\u00edsicas? Repasa las t\u00e9cnicas de anonimizaci\u00f3n y escoge la m\u00e1s adecuada atendiendo las circunstancias para evitar la imposibilidad de identificar al titular originario de la informaci\u00f3n tratada.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Si quieres saber m\u00e1s sobre el tema o te ha surgido alguna pregunta, \u00a1no dudes en contactarnos!<\/p>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\"><p class=\"wpcf7-contact-form-not-found\"><strong>Error:<\/strong> Formulario de contacto no encontrado.<\/p><\/div>\n\n\n\n<h6 class=\"wp-block-heading\">Informaci\u00f3n sobre protecci\u00f3n de datos<\/h6>\n\n\n\n<p class=\"wp-block-paragraph\"><small><strong>Denominaci\u00f3n social<\/strong><br>LEGAL IT GLOBAL 2017, SLP<br><\/small><small><strong>Finalidad<br><\/strong><\/small><small>Prestar el servicio.<br><\/small><small>Env\u00edo del Bolet\u00edn informativo.<br><\/small><small><strong>Legitimizaci\u00f3n<br><\/strong>Cumplimiento de la prestaci\u00f3n del servicio.<br>Consentimiento.<br><\/small><small><strong>Destinatarios<\/strong><br>Tus datos no ser\u00e1n compartidos con ning\u00fan tercero, salvo aquellos proveedores de servicios con los que disponemos de un contrato de servicios vigente.<\/small><br><small><strong>Derechos<\/strong><br>Puedes acceder, rectificar o suprimir los datos, as\u00ed como ejercer los derechos que se mencionan en nuestra Pol\u00edtica de Privacidad.<\/small><br><small><strong>M\u00e1s informaci\u00f3n<\/strong><br>Consulta la&nbsp;<a href=\"https:\/\/www.rosello-mallol.com\/es\/politica-privacidad\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pol\u00edtica de Privacidad<\/a>.<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo a lo establecido en el Considerando 26 del RGPD, la normativa de protecci\u00f3n de datos y el RGPD en particular no se aplica a los datos an\u00f3nimos o anonimizados. Pero, \u00bfqu\u00e9 son y cu\u00e1ndo puede entenderse que un conjunto de informaci\u00f3n tiene esta caracter\u00edstica? Trataremos de resolverlo en este post: \u00bfQu\u00e9 son los [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":18261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_joinchat":[],"footnotes":""},"categories":[209],"tags":[241,1208,640,1206,1209,704,399,639,1210,236,711],"class_list":["post-18263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-aepd-es","tag-anonimizados","tag-datos-es","tag-datos-anonimos","tag-datos-seudonimizados","tag-normativa-es","tag-privacidad-2","tag-proteccion-de-datos-es","tag-pseudonimizado","tag-rgpd-es","tag-ue-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Datos an\u00f3nimos: \u00bfQu\u00e9 son? | Rosell\u00f3 Mallol Abogados<\/title>\n<meta name=\"description\" content=\"\u00bfSabes qu\u00e9 son los datos an\u00f3nimos? \u00a1Entra y con\u00f3celos, ya que no se les aplica el RGPD y pueden ser muy \u00fatiles para vosotros!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datos an\u00f3nimos: \u00bfQu\u00e9 son?\" \/>\n<meta property=\"og:description\" content=\"De acuerdo a lo establecido en el Considerando 26 del RGPD, la normativa de protecci\u00f3n de datos y el RGPD en particular no se aplica a los datos an\u00f3nimos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/\" \/>\n<meta property=\"og:site_name\" content=\"Rosell\u00f3 Mallol\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-16T09:30:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-16T09:30:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/blake-guidry-jXxdtXFEjcc-unsplash-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vic_rosello\" \/>\n<meta name=\"twitter:site\" content=\"@vic_rosello\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Datos an\u00f3nimos: \u00bfQu\u00e9 son? | Rosell\u00f3 Mallol Abogados","description":"\u00bfSabes qu\u00e9 son los datos an\u00f3nimos? \u00a1Entra y con\u00f3celos, ya que no se les aplica el RGPD y pueden ser muy \u00fatiles para vosotros!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/","og_locale":"es_ES","og_type":"article","og_title":"Datos an\u00f3nimos: \u00bfQu\u00e9 son?","og_description":"De acuerdo a lo establecido en el Considerando 26 del RGPD, la normativa de protecci\u00f3n de datos y el RGPD en particular no se aplica a los datos an\u00f3nimos","og_url":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/","og_site_name":"Rosell\u00f3 Mallol","article_published_time":"2023-02-16T09:30:48+00:00","article_modified_time":"2023-02-16T09:30:51+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/blake-guidry-jXxdtXFEjcc-unsplash-1.jpg","type":"image\/jpeg"}],"author":"Marketing","twitter_card":"summary_large_image","twitter_creator":"@vic_rosello","twitter_site":"@vic_rosello","twitter_misc":{"Escrito por":"Marketing","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/#article","isPartOf":{"@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/"},"author":{"name":"Marketing","@id":"https:\/\/www.rosello-mallol.com\/es\/#\/schema\/person\/54fe3a9119386ad1ec22a0f09bc21147"},"headline":"Datos an\u00f3nimos: \u00bfQu\u00e9 son?","datePublished":"2023-02-16T09:30:48+00:00","dateModified":"2023-02-16T09:30:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/"},"wordCount":736,"publisher":{"@id":"https:\/\/www.rosello-mallol.com\/es\/#organization"},"image":{"@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/blake-guidry-jXxdtXFEjcc-unsplash-1.jpg","keywords":["aepd","anonimizados","datos","Datos an\u00f3nimos","datos seudonimizados","normativa","privacidad","Protecci\u00f3n de datos","pseudonimizado","RGPD","UE"],"articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/","url":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/","name":"Datos an\u00f3nimos: \u00bfQu\u00e9 son? | Rosell\u00f3 Mallol Abogados","isPartOf":{"@id":"https:\/\/www.rosello-mallol.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/#primaryimage"},"image":{"@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/blake-guidry-jXxdtXFEjcc-unsplash-1.jpg","datePublished":"2023-02-16T09:30:48+00:00","dateModified":"2023-02-16T09:30:51+00:00","description":"\u00bfSabes qu\u00e9 son los datos an\u00f3nimos? \u00a1Entra y con\u00f3celos, ya que no se les aplica el RGPD y pueden ser muy \u00fatiles para vosotros!","breadcrumb":{"@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/#primaryimage","url":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/blake-guidry-jXxdtXFEjcc-unsplash-1.jpg","contentUrl":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/blake-guidry-jXxdtXFEjcc-unsplash-1.jpg","width":1920,"height":1280,"caption":"Datos an\u00f3nimos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rosello-mallol.com\/es\/datos-anonimos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rosello-mallol.com\/es\/"},{"@type":"ListItem","position":2,"name":"Datos an\u00f3nimos: \u00bfQu\u00e9 son?"}]},{"@type":"WebSite","@id":"https:\/\/www.rosello-mallol.com\/es\/#website","url":"https:\/\/www.rosello-mallol.com\/es\/","name":"Rosell\u00f3 Mallol","description":"Despatx advocats experts en TIC i Protecci\u00f3 de dades","publisher":{"@id":"https:\/\/www.rosello-mallol.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rosello-mallol.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rosello-mallol.com\/es\/#organization","name":"Rosell\u00f3 Mallol - Advocats especialistes en dret digital","url":"https:\/\/www.rosello-mallol.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rosello-mallol.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/logo-definitiu-web.png","contentUrl":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/logo-definitiu-web.png","width":4000,"height":736,"caption":"Rosell\u00f3 Mallol - Advocats especialistes en dret digital"},"image":{"@id":"https:\/\/www.rosello-mallol.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/vic_rosello","https:\/\/www.instagram.com\/rosellomallol\/","https:\/\/www.linkedin.com\/in\/victorrosello\/","https:\/\/www.youtube.com\/channel\/UCxcqAdksWzsEaZ5UYoFJd0Q\/featured"]},{"@type":"Person","@id":"https:\/\/www.rosello-mallol.com\/es\/#\/schema\/person\/54fe3a9119386ad1ec22a0f09bc21147","name":"Marketing","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/337d1590ee4f05238bd6449f6d1442bd1df14a6fdeceb5aaa29f47c8a4598d96?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/337d1590ee4f05238bd6449f6d1442bd1df14a6fdeceb5aaa29f47c8a4598d96?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/337d1590ee4f05238bd6449f6d1442bd1df14a6fdeceb5aaa29f47c8a4598d96?s=96&d=mm&r=g","caption":"Marketing"},"url":"https:\/\/www.rosello-mallol.com\/es\/author\/marketing\/"}]}},"jetpack_featured_media_url":"https:\/\/www.rosello-mallol.com\/wp-content\/uploads\/blake-guidry-jXxdtXFEjcc-unsplash-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/posts\/18263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/comments?post=18263"}],"version-history":[{"count":0,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/posts\/18263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/media\/18261"}],"wp:attachment":[{"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/media?parent=18263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/categories?post=18263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rosello-mallol.com\/es\/wp-json\/wp\/v2\/tags?post=18263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}